{"id":467150,"date":"2026-07-15T13:31:49","date_gmt":"2026-07-15T16:31:49","modified":"2026-07-15T16:56:52","modified_gmt":"2026-07-15T19:56:52","slug":"maior-evento-de-jovens-adventistas-do-rio-celebra-8a-edicao-neste-sabado","status":"publish","type":"post","link":"https:\/\/noticias.adventistas.org\/pt\/maior-evento-de-jovens-adventistas-do-rio-celebra-8a-edicao-neste-sabado\/","title":{"rendered":"Rio In Power tem sua 8\u00aa edi\u00e7\u00e3o nesse s\u00e1bado"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/54432942818_dd6ece1917_c.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"533\" src=\"https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/54432942818_dd6ece1917_c.jpg\" alt=\"\" class=\"wp-image-467178\" srcset=\"https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/54432942818_dd6ece1917_c.jpg 799w, https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/54432942818_dd6ece1917_c-768x512.jpg 768w\" sizes=\"(max-width: 799px) 100vw, 799px\" \/><\/a><figcaption class=\"wp-element-caption\">Edic\u00e3o de 2025 reuniu uma multid\u00e3o de jovens adventistas na Barra da Tijuca (Foto: Danylo Duarte)<\/figcaption><\/figure>\n\n\n\n<p>O Rio In Power deve se consolidar como o maior encontro de jovens adventistas do Rio de Janeiro, reunindo 2 mil pessoas na casa de eventos Ribalta, na Barra da Tijuca, zona Sudoeste da Capital. Esse ano, evento prop\u00f5e encerrar a Semana Jovem n\u00e3o apenas como celebra\u00e7\u00e3o, mas como um chamado \u00e0 miss\u00e3o. O encontro contar\u00e1 com a participa\u00e7\u00e3o dos cantores Rayssa Andreoli e S\u00e9rgio Saas e ter\u00e1 in\u00edcio \u00e0s 9h.<\/p>\n\n\n\n<p>Para o pastor Maicon Galantini, l\u00edder dos jovens adventistas no Sul do Rio de Janeiro, h\u00e1 muitos motivos para celebrar a juventude sul-fluminense.<\/p>\n\n\n\n<p>\"Os jovens hoje t\u00eam muito com que se envolver e com que se distrair. Podem se envolver apenas pensando nesta vida, como faculdade, trabalho, crescer na vida, ou podem se envolver com as divers\u00f5es seculares. Mas n\u00f3s temos uma comunidade de jovens que, numa sociedade t\u00e3o imediatista, da velocidade das redes sociais, do feed que n\u00e3o para, dos v\u00eddeos r\u00e1pidos e de pouca profundidade, mant\u00eam a capacidade de pensar naquilo que \u00e9 eterno e na salva\u00e7\u00e3o das pessoas.\", avaliou Galantini.<\/p>\n\n\n\n<p>Ainda segundo o l\u00edder, \"s\u00e3o jovens que creem profundamente e amam profundamente Jesus Cristo, que esperam a Sua volta e entendem que a nossa miss\u00e3o \u00e9 pregar o evangelho a todos, como foi a ordem de Cristo. Por isso temos tanto a celebrar neste Dia do Jovem Adventista, e por isso um evento como o Rio In Power \u00e9 t\u00e3o importante para essa celebra\u00e7\u00e3o\", completou. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/54431840792_fffd3af14a_c-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"533\" src=\"https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/54431840792_fffd3af14a_c-1.jpg\" alt=\"\" class=\"wp-image-467244\" srcset=\"https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/54431840792_fffd3af14a_c-1.jpg 799w, https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/54431840792_fffd3af14a_c-1-768x512.jpg 768w\" sizes=\"(max-width: 799px) 100vw, 799px\" \/><\/a><figcaption class=\"wp-element-caption\">H\u00e1 oito anos, o Rio In Power \u00e9 o evento que marca o encontro dos jovens adventistas do Sul do Rio (Foto: Danylo Duarte)<\/figcaption><\/figure>\n\n\n\n<p>At\u00e9 o fechamento dessa mat\u00e9ria, mais de 1,6 mil pessoas j\u00e1 haviam feito suas inscri\u00e7\u00f5es e garantido seu lugar no evento. A estudante Maria Clara Rocha, de 16 anos, \u00e9 uma delas. \"Estava viajando de f\u00e9rias, mas retornei essa semana para participar do Rio In Power. Estou contando os dias para o s\u00e1bado chegar\", contou. <\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es continuam abertas por R$ 40 e podem ser feitas pelo link: <a href=\"http:\/\/e-inscricao.com\/ars-eventos\/rio-in-power2026\">e-inscricao.com\/ars-eventos\/rio-in-power2026<\/a>. As vagas s\u00e3o limitadas e a organiza\u00e7\u00e3o recomenda garantir o quanto antes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">Servi\u00e7o<\/h2>\n\n\n\n<p>Endere\u00e7o: Ribalta Eventos \u2014 Av. das Am\u00e9ricas, 9650, Barra da Tijuca<br>Hor\u00e1rio<strong>:<\/strong> 9h \u00e0s 16h<br>Inscri\u00e7\u00f5es: R$ 40 \u2014 e-inscricao.com\/ars-eventos\/rio-in-power2026<br>Estacionamento: local, com capacidade para at\u00e9 400 ve\u00edculos, a partir de R$30<br>Transporte p\u00fablico: Esta\u00e7\u00e3o Riomar do BRT (Transoeste), a poucos metros da entrada<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/RIO-15-x-10-cm-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"886\" height=\"540\" src=\"https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/RIO-15-x-10-cm-3-886x540.png\" alt=\"\" class=\"wp-image-467179\" \/><\/a><figcaption class=\"wp-element-caption\">Rayssa Andreoli e Sergio Saas estar\u00e3o no palco do Rio In Power 2026 (Foto: Divulga\u00e7\u00e3o)<\/figcaption><\/figure>\n\n\n\n<p class=\"has-medium-font-size\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evento deve reunir at\u00e9 2 mil em um dia de celebra\u00e7\u00e3o pelo Dia Mundial do Jovem Adventista<\/p>\n","protected":false},"author":495,"featured_media":467177,"comment_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"xtt-pa-format":[3876],"xtt-pa-classification":[4023],"xtt-pa-editorias":[3999,4014],"xtt-pa-departamentos":[45],"xtt-pa-projetos":[],"xtt-pa-regiao":[92],"xtt-pa-sedes":[178],"xtt-pa-owner":[3696],"class_list":["post-467150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","xtt-pa-format-noticia","xtt-pa-classification-institucional","xtt-pa-editorias-eventos-3","xtt-pa-editorias-jovem","xtt-pa-departamentos-ministerio-jovem","xtt-pa-regiao-rio-de-janeiro","xtt-pa-sedes-ars","xtt-pa-owner-associacao-rio-sul"],"acf":{"custom_author":"Marcely Seixas","embed_url":"","embed_length":""},"terms":{"editorial":"Eventos","format":"Not\u00edcia"},"featured_media_url":{"full":"https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/54431840792_fffd3af14a_c.jpg","medium":"https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/54431840792_fffd3af14a_c-768x512.jpg","small":"https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/54431840792_fffd3af14a_c-240x135.jpg","pa-block-preview":"https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/54431840792_fffd3af14a_c-240x135.jpg","pa-block-render":"https:\/\/files.adventistas.org\/noticias\/pt\/2026\/07\/54431840792_fffd3af14a_c-480x270.jpg"}}