{"id":184228,"date":"2016-12-02T13:55:53","date_gmt":"2016-12-02T16:55:53","modified":"2025-01-15T18:53:42","modified_gmt":"2025-01-15T21:53:42","slug":"c-s-lewis-e-o-drama-da-chapecoense","status":"publish","type":"post","link":"https:\/\/noticias.adventistas.org\/pt\/coluna\/rafael.rossi\/c-s-lewis-e-o-drama-da-chapecoense\/","title":{"rendered":"C. S. Lewis e o drama da Chapecoense"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/files.adventistas.org\/noticias\/pt\/2016\/12\/shutterstock_1677618448.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/files.adventistas.org\/noticias\/pt\/2016\/12\/shutterstock_1677618448.jpg\" alt=\"\" class=\"wp-image-401525\" srcset=\"https:\/\/files.adventistas.org\/noticias\/pt\/2016\/12\/shutterstock_1677618448.jpg 1000w, https:\/\/files.adventistas.org\/noticias\/pt\/2016\/12\/shutterstock_1677618448-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption class=\"wp-element-caption\">O sofrimento, embora desafiador, ensina a fragilidade da vida e nos lembra que Deus est\u00e1 conosco, esperando por nossa miss\u00e3o de pregar o evangelho at\u00e9 a volta de Cristo. (Foto: Shutterstock)<\/figcaption><\/figure>\n\n\n\n<p>Na semana do falecimento de um grande pregador crist\u00e3o acontece uma trag\u00e9dia que levanta o questionamento: Onde est\u00e1 Deus quando as pessoas sofrem?<\/p>\n\n\n\n<p>Clive Staples Lewis, comumente mais referido como&nbsp;C. S. Lewis&nbsp;(Belfast,&nbsp;29 de novembro&nbsp;de&nbsp;1898&nbsp;\u2014&nbsp;Oxford,&nbsp;22 de novembro&nbsp;de&nbsp;1963), foi um&nbsp;professor universit\u00e1rio,&nbsp;escritor,&nbsp;romancista,&nbsp;poeta,&nbsp;cr\u00edtico liter\u00e1rio,&nbsp;ensa\u00edsta&nbsp;e&nbsp;apologista crist\u00e3o&nbsp;brit\u00e2nico. Apesar de ter sido criado ao longo da inf\u00e2ncia dentro das tradi\u00e7\u00f5es da&nbsp;Igreja da Irlanda, se tornou um&nbsp;ateu&nbsp;convicto na sua adolesc\u00eancia.<\/p>\n\n\n\n<p>Lewis voltou \u00e0 f\u00e9 crist\u00e3 no in\u00edcio da&nbsp;d\u00e9cada de 1930, por influ\u00eancia de seu amigo J. R. R. Tolkien, que o levou a perceber que o cristianismo era um \u201cmito verdadeiro\u201d. Como pensador, ele lutava com os questionamentos ontol\u00f3gicos da vida. Um deles \u00e9 o porqu\u00ea do sofrimento.<\/p>\n\n\n\n<p>Em seu livro <em>O problema do sofrimento<\/em> est\u00e1 uma das suas frases mais famosas: \u201cDeus sussurra em nossos prazeres, fala em nossa consci\u00eancia, mas grita em nossas horas de sofrimento: esse \u00e9 seu megafone para despertar um mundo surdo.\u201d<\/p>\n\n\n\n<p>A publica\u00e7\u00e3o come\u00e7a com Lewis relembrando seu tempo de ate\u00edsmo. Em todos os cap\u00edtulos ele levanta o tema n\u00e3o respondido do \u201csofrimento humano ante um c\u00e9u aparentemente surdo e um Deus silencioso.\u201d<\/p>\n\n\n\n<p>No passado ele acreditou que o universo era um local f\u00fatil, de frio e escurid\u00e3o, de mis\u00e9ria e sofrimento. Para ele havia um espet\u00e1culo sem sentido de civiliza\u00e7\u00f5es surgindo e desaparecendo, da ra\u00e7a humana que a ci\u00eancia condena a uma extin\u00e7\u00e3o final e de um universo fadado \u00e0 morte. Vinte anos antes de escrever <em>O problema do sofrimento<\/em>, Lewis conclu\u00eda que \u201cou n\u00e3o existe esp\u00edrito nenhum por tr\u00e1s do universo ou ent\u00e3o existe um esp\u00edrito indiferente ao bem e ao mal ou ent\u00e3o existe esp\u00edrito mau.\u201d<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Deus \u00e9 bom?<\/strong><\/h4>\n\n\n\n<p>Essa mesma linha de pensamento levava a uma outra indaga\u00e7\u00e3o: \u201cSe o universo \u00e9 t\u00e3o ruim, como foi poss\u00edvel que seres humanos um dia come\u00e7assem a atribuir a atua\u00e7\u00e3o de um Criador s\u00e1bio e bom?\u201d<\/p>\n\n\n\n<p>O sofrimento cria um problema para a humanidade sofredora. \u201cSe Deus fosse bom, ele iria querer tornar as suas criaturas perfeitamente felizes, e se Deus fosse todo-poderoso, ele seria capaz de fazer o que desejasse. Mas as criaturas n\u00e3o s\u00e3o felizes. Por isso Deus n\u00e3o tem nem bondade e nem poder\u201d, escreveu.<\/p>\n\n\n\n<p>Para Lewis, as pessoas confundem, com demasiada facilidade, bondade com benevol\u00eancia, e assim abordam o problema do sofrimento partindo de uma perspectiva falsa. A bondade de Deus significa que n\u00f3s precisamos ver a n\u00f3s mesmos como objetos de seu amor, n\u00e3o como objetos de um indiferente projeto divino de bem-estar. H\u00e1 quatro dimens\u00f5es acerca do amor de Deus por n\u00f3s:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>O amor de um artista por aquilo que criou;<\/li>\n\n\n\n<li>O amor de um ser humano por um animal;<\/li>\n\n\n\n<li>O amor de um pai por um filho;<\/li>\n\n\n\n<li>O amor de um homem por uma mulher;<\/li>\n<\/ol>\n\n\n\n<p>Nosso problema \u00e9 que n\u00e3o queremos ser perturbados, n\u00e3o queremos ser amados de forma t\u00e3o apaixonada assim. \u201cVoc\u00ea pediu um Deus amoroso, voc\u00ea o tem.\u201d<\/p>\n\n\n\n<p>\u201cO mundo \u00e9 uma dan\u00e7a em que o bem, provindo de Deus, \u00e9 atrapalhado pelo mal que prov\u00e9m das criaturas, e o conflito resultante \u00e9 resolvido pela pr\u00f3pria ado\u00e7\u00e3o por Deus da natureza sofredora que o mal produz. A doutrina da queda livre afirma que o mal produz o combust\u00edvel ou a mat\u00e9ria prima da segunda e mais completa esp\u00e9cie de bem n\u00e3o \u00e9 uma contribui\u00e7\u00e3o de Deus, mas sim do homem.\u201d<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Li\u00e7\u00f5es a partir do sofrimento<\/strong><\/h4>\n\n\n\n<p>Lewis considera que o sofrimento pode nos ensinar. Isso n\u00e3o deve ser entendido como uma defesa de Deus diante do sofrimento, mas como uma tentativa de perguntar de que maneira podemos lidar com o sofrimento.<\/p>\n\n\n\n<p>Ele pode nos fazer ver a fragilidade e transitoriedade de nossa exist\u00eancia e desafiar nossa cren\u00e7a de que podemos nos safar impunimente por m\u00e9ritos pr\u00f3prios. Assim, o sofrimento nos ajuda a desfazer a ilus\u00e3o de que \u201cest\u00e1 tudo bem\u201d, permitindo que Deus \u201cplante a bandeira da verdade dentro da fortaleza de uma alma rebelde.\u201d<\/p>\n\n\n\n<p><em>O problema do sofrimento<\/em> foi, aos poucos, sendo aceito como como uma resposta crist\u00e3 ao assunto. O livro tem as suas falhas e exageros, no entanto, muitos encontraram nesses argumentos uma voz que compreendia as preocupa\u00e7\u00f5es e tranquilizava pelas respostas.<\/p>\n\n\n\n<p>Toda essa base ganhou repercuss\u00e3o durante a Segunda Guerra Mundial, quando Lewis faz uma s\u00e9rie de palestras na BBC de Londres. Os temas apresentados formariam o livro <em>Cristianismo Puro e Simples<\/em>.<\/p>\n\n\n\n<p>As quatro primeiras palestras foram ao ar em 1941:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>06 de agosto: Dec\u00eancia B\u00e1sica<\/li>\n\n\n\n<li>13 de agosto: Lei cient\u00edfica e lei moral<\/li>\n\n\n\n<li>20 de agosto: Materialismo e Religi\u00e3o<\/li>\n\n\n\n<li>27 de agosto: O que podemos fazer sobre isso?<\/li>\n<\/ol>\n\n\n\n<p>Essas apresenta\u00e7\u00f5es se destinavam a ouvintes da Noruega ocupada pelos nazistas. Ele tornou-se a voz da f\u00e9 para muitas pessoas que sofriam. Foi na B\u00edblia que a esperan\u00e7a surgiu.<\/p>\n\n\n\n<p>As trag\u00e9dias despertam em n\u00f3s a como\u00e7\u00e3o. O que aconteceu com o Chapecoense faz ressurgir quest\u00f5es que tentam colocar Deus em cheque. O que Deus tem para n\u00f3s extrapola os limites do que sabemos, vemos ou um dia ouvimos. Deus sofre quando sofremos e quer colocar um ponto final nessa hist\u00f3ria de dor.<\/p>\n\n\n\n<p>O que nos separa da volta de Jesus \u00e9 a prega\u00e7\u00e3o do evangelho e essa \u00e9 a miss\u00e3o que cada crist\u00e3o recebeu das m\u00e3os do Senhor. Enquanto Jesus n\u00e3o volta, teremos que conviver com as trag\u00e9dias, mas elas definitivamente nos mostram que aqui n\u00e3o \u00e9 o nosso lugar.<\/p>\n\n\n\n<p>\u201cCrede no Senhor vosso Deus e estareis seguros...\u201d. (2 Cr\u00f4nicas 20:20).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A problem\u00e1tica ainda traz questionamentos, mas tamb\u00e9m desperta esperan\u00e7a<\/p>\n","protected":false},"author":13,"featured_media":401525,"comment_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"xtt-pa-format":[3879],"xtt-pa-classification":[],"xtt-pa-editorias":[3668],"xtt-pa-departamentos":[],"xtt-pa-projetos":[],"xtt-pa-regiao":[],"xtt-pa-sedes":[119],"xtt-pa-owner":[1170],"class_list":["post-184228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","xtt-pa-format-coluna","xtt-pa-editorias-biblia","xtt-pa-sedes-dsa","xtt-pa-owner-divisao-sul-americana"],"acf":{"embed_url":"","embed_length":"","custom_author":""},"terms":{"editorial":"B\u00edblia","format":"Coluna"},"featured_media_url":{"full":"https:\/\/files.adventistas.org\/noticias\/pt\/2016\/12\/shutterstock_1677618448.jpg","medium":"https:\/\/files.adventistas.org\/noticias\/pt\/2016\/12\/shutterstock_1677618448-768x512.jpg","small":"https:\/\/files.adventistas.org\/noticias\/pt\/2016\/12\/shutterstock_1677618448-240x135.jpg","pa-block-preview":"https:\/\/files.adventistas.org\/noticias\/pt\/2016\/12\/shutterstock_1677618448-240x135.jpg","pa-block-render":"https:\/\/files.adventistas.org\/noticias\/pt\/2016\/12\/shutterstock_1677618448-480x270.jpg"}}