{"id":12063,"date":"2014-01-15T09:52:28","date_gmt":"2014-01-15T12:52:28","modified":"2025-01-31T16:29:37","modified_gmt":"2025-01-31T19:29:37","slug":"ovo-lacto-vegetariano-lacto-vegetariano-o-vegano","status":"publish","type":"post","link":"https:\/\/noticias.adventistas.org\/es\/columna\/hildemar.santos\/ovo-lacto-vegetariano-lacto-vegetariano-o-vegano\/","title":{"rendered":"\u00bfOvo lacto vegetariano, lacto vegetariano o vegano?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/files.adventistas.org\/noticias\/es\/2014\/01\/31162909\/shutterstock_1129556930-960x540.jpg\" alt=\"\" class=\"wp-image-97530\" srcset=\"https:\/\/files.adventistas.org\/noticias\/es\/2014\/01\/31162909\/shutterstock_1129556930-960x540.jpg 960w, https:\/\/files.adventistas.org\/noticias\/es\/2014\/01\/31162909\/shutterstock_1129556930-480x270.jpg 480w, https:\/\/files.adventistas.org\/noticias\/es\/2014\/01\/31162909\/shutterstock_1129556930-240x135.jpg 240w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption class=\"wp-element-caption\">A dieta vegetariana traz benef\u00edcios comprovados para a sa\u00fade, ajudando a prevenir e at\u00e9 reverter doen\u00e7as metab\u00f3licas e cardiovasculares.(Foto: Shutterstock)<\/figcaption><\/figure>\n\n\n\n<p>Finalmente me hice vegano. Los \u00faltimos resultados del Estudio Adventista de Salud II demostraron que los veganos, o vegetarianos totales, los cuales no consumen ning\u00fan producto de origen animal, tienen mejor nivel de colesterol, de LDL o colesterol malo, de triglic\u00e9ridos, glucosa, presi\u00f3n arterial, peso, y nivel alto de colesterol bueno o HDL cuando es comparado con los otros tipos de dieta com\u00fan entre los adventistas (ovo lacto, lacto, pescovegetarianos y omn\u00edvoros).<\/p>\n\n\n\n<p>En la \u00faltima conferencia del Colegio Americano de Medicina del Estilo de Vida (ACLM), esta tendencia tambi\u00e9n fue confirmada. Y hay m\u00e1s, la dieta vegana es capaz de revertir una serie de enfermedades relacionadas con el estilo de vida. El doctor Esselstyn, de la Cl\u00ednica Cleveland en Ohio, Estados Unidos, prob\u00f3 que es posible reabrir las arterias coronarias tapadas con placas de colesterol simplemente adoptando una dieta exclusiva a base de vegetales (vegana). El doctor Ornish fue incluso m\u00e1s all\u00e1, investigando el efecto de este tipo de dieta en la reversi\u00f3n y control del c\u00e1ncer de pr\u00f3stata. El doctor Youngberg present\u00f3 su experiencia en la reversi\u00f3n de la diabetes con el mismo estilo de dieta asociada con el adecuado ejercicio.<\/p>\n\n\n\n<p>La dieta vegana es capaz de revertir casos nuevos de diabetes y reducir el riesgo de complicaciones del diab\u00e9tico, como la retinopat\u00eda, la insuficiencia renal, la ceguera y enfermedades coronarias. En algunos casos, estas complicaciones pueden ser revertidas.<\/p>\n\n\n\n<p>En mi experiencia pr\u00e1ctica como m\u00e9dico y nutricionista (ahora tengo el t\u00edtulo de nutricionista aqu\u00ed en los Estados Unidos), siempre prescrib\u00eda esta dieta a pacientes con las enfermedades mencionadas anteriormente. Por ejemplo, cuando era director de la Cl\u00ednica Adventista de San Roque, para quien ten\u00eda c\u00e1ncer, diabetes y problemas cardiacos, la dieta vegetariana total era siempre la indicada.<\/p>\n\n\n\n<p>En Hong Kong, de la misma manera, prescrib\u00edamos el r\u00e9gimen vegetariano total usando los principios del <i>New Start<\/i> (ocho remedios naturales) promovidos por el Instituto Weymar, de California, Estados Unidos, los cuales son vegetarianos estrictos. Tuvimos varios casos de diab\u00e9ticos que dejaron sus remedios y lograron controlar su glucosa solo con dieta, ejercicio y hierbas medicinales.<\/p>\n\n\n\n<p>En mi experiencia personal, fui vegano por algunos a\u00f1os cuando era joven, despu\u00e9s, continu\u00e9 vegetariano por varios a\u00f1os. En realidad, comenc\u00e9 a ser vegetariano a los 18 a\u00f1os. As\u00ed que son m\u00e1s de 40 a\u00f1os de vegetarianismo. Ahora usted tambi\u00e9n podr\u00e1 calcular mi edad.<\/p>\n\n\n\n<p>En mi familia tenemos una epidemia de diabetes por parte de mi padre, el cual era diab\u00e9tico, perdi\u00f3 su visi\u00f3n, ten\u00eda polineuropat\u00eda gastrointestinal con diarrea cr\u00f3nica y al final perdi\u00f3 su vida en una cirug\u00eda de amputaci\u00f3n por causa de una gangrena en el pi\u00e9. Una tragedia total, \u00bfno es verdad? De esta manera, poniendo todas las \u201ccartas sobre la mesa\u201d, resolv\u00ed dejar los alimentos animales. Decid\u00ed volver al r\u00e9gimen vegetariano total.<\/p>\n\n\n\n<p>Pienso que la decisi\u00f3n fue correcta, pero tengo cuidado en aconsejar a otros en el mismo sentido. As\u00ed que si una persona est\u00e1 con exceso de peso y riesgo de anormalidades metab\u00f3licas, o con el s\u00edndrome metab\u00f3lico (diabetes, colesterol, triglic\u00e9ridos, sobre peso abdominal y presi\u00f3n alta), el camino es la dieta vegetariana total.<\/p>\n\n\n\n<p>Sin embargo, si no tiene condiciones de seguirla por razones financieras o incluso por dificultades en encontrar los alimentos para sustituir los animales, siga en un r\u00e9gimen m\u00e1s mezclado, pero aumente el consumo de vegetales, frutas, nueces, granos integrales, frejoles y ra\u00edces.<\/p>\n\n\n\n<p>Aqu\u00ed, en nuestra cl\u00ednica en Loma Linda, tenemos un programa llamado <i>Dieta del plato lleno<\/i>, en el que aconsejamos que la persona coma 40 gramos de fibra por d\u00eda, o sea, entre la mitad y 3\/4 de su plato, en todas las comidas, debe estar constituido de alimentos vegetarianos fibrosos, en realidad, todos aquellos mencionados anteriormente.<\/p>\n\n\n\n<p>Por lo tanto amigo, es tiempo de cambiar, por lo menos para m\u00ed. Un consejo importante: no se vuelva \u201cveg\u00e1tico\u201d o vegano mezclado con fan\u00e1tico. Yo ya fui \u201cveg\u00e1tico\u201d y tuve buenos resultados con algunos pacientes y amigos, sin embargo, siempre era visto como una persona extremista en que todo rodeaba sobre alimentaci\u00f3n y vegetarianismo. Sea estricto consigo mismo, pero tenga cuidado en presionar a otros a hacer algunos cambios alimenticios. El ejemplo habla m\u00e1s alto y la amistad, el amor y la compasi\u00f3n deben venir antes que la \u201cprescripci\u00f3n\u201d.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalmente me hice vegano. Los \u00faltimos resultados del Estudio Adventista de Salud II demostraron que los veganos, o vegetarianos totales, los cuales no consumen ning\u00fan producto de origen animal, tienen mejor nivel de colesterol, de LDL o colesterol malo, de triglic\u00e9ridos, glucosa, presi\u00f3n arterial, peso, y nivel alto de colesterol bueno o HDL cuando es [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":97530,"comment_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"xtt-pa-format":[5185],"xtt-pa-classification":[],"xtt-pa-editorias":[3391],"xtt-pa-departamentos":[],"xtt-pa-projetos":[],"xtt-pa-regiao":[],"xtt-pa-sedes":[256],"xtt-pa-owner":[3471],"class_list":["post-12063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","xtt-pa-format-columna","xtt-pa-editorias-salud","xtt-pa-sedes-dsa","xtt-pa-owner-division-sudamericana"],"acf":{"embed_url":"","embed_length":"","custom_author":""},"terms":{"editorial":"Salud","format":"Columna"},"featured_media_url":{"full":"https:\/\/files.adventistas.org\/noticias\/es\/2014\/01\/31162909\/shutterstock_1129556930.jpg","medium":"https:\/\/files.adventistas.org\/noticias\/es\/2014\/01\/31162909\/shutterstock_1129556930-768x512.jpg","small":"https:\/\/files.adventistas.org\/noticias\/es\/2014\/01\/31162909\/shutterstock_1129556930-240x135.jpg","pa-block-preview":"https:\/\/files.adventistas.org\/noticias\/es\/2014\/01\/31162909\/shutterstock_1129556930-240x135.jpg","pa-block-render":"https:\/\/files.adventistas.org\/noticias\/es\/2014\/01\/31162909\/shutterstock_1129556930-480x270.jpg"}}